{"id":2281,"date":"2020-10-20T11:41:16","date_gmt":"2020-10-20T17:41:16","guid":{"rendered":"http:\/\/elcazadorguatemala.com\/gt\/?post_type=product&#038;p=2281"},"modified":"2023-04-05T10:44:49","modified_gmt":"2023-04-05T16:44:49","slug":"correa-de-conversion-utg-bolla-de-2-a-1-puntos-qd-negra","status":"publish","type":"product","link":"https:\/\/elcazadorguatemala.com\/gt\/product\/correa-de-conversion-utg-bolla-de-2-a-1-puntos-qd-negra\/","title":{"rendered":"Correa de conversi\u00f3n UTG\u00ae BOLLA \u2122 de 2 a 1 puntos QD, negra"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Ajustable en longitud de 42 \u00ab-58\u00bb, cinta de poli\u00e9ster de 1,2 \u00abde ancho de color negro mate con una parte del cabestrillo acolchada para mayor comodidad<br \/>\n\u2022 Control deslizante de acero liviano con anillo en D de gran tama\u00f1o y correa de tracci\u00f3n Ajusta la tensi\u00f3n de la eslinga de manera intuitiva y r\u00e1pida tirando hacia adelante para aumentar la holgura y la longitud y hacia atr\u00e1s para disminuir<br \/>\n\u2022 Eslingas giratorias de acero QD y un Ambi. La carcasa giratoria QD convierte f\u00e1cilmente la eslinga de una configuraci\u00f3n de 2 puntos a 1 punto<\/p>\n","protected":false},"featured_media":2282,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[71],"product_tag":[962,247],"class_list":{"0":"post-2281","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-correas","7":"product_tag-correa-de-conversion-utg-bolla-de-2-a-1-puntos-qd","8":"product_tag-negra","10":"first","11":"outofstock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/product\/2281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/comments?post=2281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/media\/2282"}],"wp:attachment":[{"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/media?parent=2281"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/product_cat?post=2281"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elcazadorguatemala.com\/gt\/wp-json\/wp\/v2\/product_tag?post=2281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}